{"id":1072,"date":"2023-09-14T10:15:19","date_gmt":"2023-09-14T09:15:19","guid":{"rendered":"https:\/\/www.wiredcpa.com\/?p=1072"},"modified":"2023-09-14T10:15:19","modified_gmt":"2023-09-14T09:15:19","slug":"date-limite-de-paiement-des-dividendes-cest-le-30-septembre","status":"publish","type":"post","link":"https:\/\/www.wiredcpa.com\/fr\/date-limite-de-paiement-des-dividendes-cest-le-30-septembre\/","title":{"rendered":"Date limite de paiement des dividendes &#8211; C\u2019est le 30 septembre"},"content":{"rendered":"<p>Quand les dividendes sont-ils dus aux associ\u00e9s\u00a0?<\/p>\n<p>Les dividendes ne sont dus que lorsque leur versement a \u00e9t\u00e9 d\u00e9cid\u00e9 au pr\u00e9alable par une assembl\u00e9e g\u00e9n\u00e9rale des associ\u00e9s, cette\u00a0d\u00e9cision\u00a0ayant d\u00fb \u00eatre vot\u00e9e par un ou plusieurs associ\u00e9s repr\u00e9sentant\u00a0plus de la moiti\u00e9\u00a0des parts sociales de la SARL.<\/p>\n<p>&nbsp;<\/p>\n<p>Combien verser aux associ\u00e9s\u00a0?<\/p>\n<p>Le montant global \u00e0 distribuer est fix\u00e9 par l&#8217;assembl\u00e9e g\u00e9n\u00e9rale d&#8217;approbation des comptes de l&#8217;exercice. Ensuite, la part de chaque associ\u00e9 est proportionnelle \u00e0 son nombre de parts dans le capital (sauf dispositions diff\u00e9rentes des statuts \u00e0 ce sujet).<\/p>\n<p>&nbsp;<\/p>\n<p>Ne pas oublier de d\u00e9duire au pr\u00e9alable de la somme \u00e0 verser \u00e0 chacun le montant des\u00a0pr\u00e9l\u00e8vements sociaux\u00a0et le cas \u00e9ch\u00e9ant du\u00a0pr\u00e9l\u00e8vement fiscal,\u00a0lesquels devront \u00eatre revers\u00e9s par votre soci\u00e9t\u00e9.<\/p>\n<p>&nbsp;<\/p>\n<p>Comment proc\u00e9der au paiement des dividendes\u00a0?<\/p>\n<p>Le paiement peut \u00eatre effectu\u00e9 par tout moyen. Il peut aussi \u00eatre effectu\u00e9 en une ou plusieurs fois, <strong>mais \u00e0 condition que la totalit\u00e9 soit vers\u00e9e dans les\u00a0neuf mois\u00a0qui suivent la cl\u00f4ture de l&#8217;exercice<\/strong>.<\/p>\n<p>&nbsp;<\/p>\n<p>Que faire lorsqu\u2019un associ\u00e9 a c\u00e9d\u00e9 ses parts\u00a0?<\/p>\n<p>Les dividendes reviennent \u00e0 l\u2019associ\u00e9 qui est propri\u00e9taire des parts, non pas \u00e0 la date de la cl\u00f4ture de l\u2019exercice, pas m\u00eame \u00e0 la date de la distribution, mais \u00e0 la date o\u00f9 l\u2019assembl\u00e9e\u00a0des associ\u00e9s a d\u00e9cid\u00e9 la distribution.<\/p>\n<p>&nbsp;<\/p>\n<p>Que faire lorsqu\u2019un associ\u00e9 est d\u00e9c\u00e9d\u00e9\u00a0?<\/p>\n<p>Les parts d\u00e9tenues par un associ\u00e9 d\u00e9c\u00e9d\u00e9 sont transmises par voie de succession \u00e0 ses\u00a0h\u00e9ritiers. Ce sont donc ces derniers qui deviennent associ\u00e9.<\/p>\n<p>&nbsp;<\/p>\n<p>Que faire lorsqu\u2019un associ\u00e9 a disparu\u00a0?<\/p>\n<p>C\u2019est \u00e0 l\u2019associ\u00e9 qu\u2019il appartient de r\u00e9clamer ses dividendes. Il dispose \u00e0 cet effet d\u2019un d\u00e9lai de\u00a05\u00a0ans\u00a0\u00e0\u00a0compter de\u00a0la\u00a0date de l\u2019assembl\u00e9e g\u00e9n\u00e9rale qui a d\u00e9cid\u00e9 leur distribution. Pass\u00e9 ce d\u00e9lai, les dividendes sont\u00a0prescrits\u00a0et redeviennent la propri\u00e9t\u00e9 de votre SARL.<\/p>\n<p>&nbsp;<\/p>\n<p>Que faire si on ne peut pas payer les dividendes dans le d\u00e9lai imparti\u00a0?<\/p>\n<p>Le g\u00e9rant peut suspendre le paiement des dividendes vot\u00e9s. Toutefois, si cette suspension a pour cons\u00e9quence d\u2019entra\u00eener un d\u00e9passement du\u00a0d\u00e9lai maximal de 9 mois, une\u00a0prolongation\u00a0de ce d\u00e9lai peut \u00eatre accord\u00e9e par d\u00e9cision de justice (art.L.232-13 du code de commerce).<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Quand les dividendes sont-ils dus aux associ\u00e9s\u00a0? Les dividendes ne sont dus que lorsque leur versement a \u00e9t\u00e9 d\u00e9cid\u00e9 au pr\u00e9alable par une assembl\u00e9e g\u00e9n\u00e9rale des associ\u00e9s, cette\u00a0d\u00e9cision\u00a0ayant d\u00fb \u00eatre vot\u00e9e par un ou plusieurs associ\u00e9s repr\u00e9sentant\u00a0plus de la moiti\u00e9\u00a0des parts sociales de la SARL. &nbsp; Combien verser aux associ\u00e9s\u00a0? Le montant global \u00e0 distribuer est fix\u00e9 par l&#8217;assembl\u00e9e g\u00e9n\u00e9rale d&#8217;approbation des comptes de l&#8217;exercice. Ensuite, la part de chaque associ\u00e9 est proportionnelle \u00e0 son nombre de parts dans le capital (sauf dispositions diff\u00e9rentes des statuts \u00e0 ce sujet). &nbsp; Ne pas oublier de d\u00e9duire au pr\u00e9alable de la somme \u00e0 verser \u00e0 chacun le montant des\u00a0pr\u00e9l\u00e8vements sociaux\u00a0et le cas \u00e9ch\u00e9ant du\u00a0pr\u00e9l\u00e8vement fiscal,\u00a0lesquels devront \u00eatre revers\u00e9s par votre soci\u00e9t\u00e9. &nbsp; Comment proc\u00e9der au paiement des dividendes\u00a0? Le paiement peut \u00eatre effectu\u00e9 par tout moyen. Il peut aussi \u00eatre effectu\u00e9 en une ou plusieurs fois, mais \u00e0 condition que la totalit\u00e9 soit vers\u00e9e dans les\u00a0neuf mois\u00a0qui suivent la cl\u00f4ture de l&#8217;exercice. &nbsp; Que faire lorsqu\u2019un associ\u00e9 a c\u00e9d\u00e9 ses parts\u00a0? Les dividendes reviennent \u00e0 l\u2019associ\u00e9 qui est propri\u00e9taire des parts, non pas \u00e0 la date de la cl\u00f4ture de l\u2019exercice, pas m\u00eame \u00e0 la date de la distribution, mais \u00e0 la [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.4.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Date limite de paiement des dividendes - C\u2019est le 30 septembre - Wired<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.wiredcpa.com\/fr\/date-limite-de-paiement-des-dividendes-cest-le-30-septembre\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Date limite de paiement des dividendes - C\u2019est le 30 septembre - Wired\" \/>\n<meta property=\"og:description\" content=\"Quand les dividendes sont-ils dus aux associ\u00e9s\u00a0? Les dividendes ne sont dus que lorsque leur versement a \u00e9t\u00e9 d\u00e9cid\u00e9 au pr\u00e9alable par une assembl\u00e9e g\u00e9n\u00e9rale des associ\u00e9s, cette\u00a0d\u00e9cision\u00a0ayant d\u00fb \u00eatre vot\u00e9e par un ou plusieurs associ\u00e9s repr\u00e9sentant\u00a0plus de la moiti\u00e9\u00a0des parts sociales de la SARL. &nbsp; Combien verser aux associ\u00e9s\u00a0? Le montant global \u00e0 distribuer est fix\u00e9 par l&#8217;assembl\u00e9e g\u00e9n\u00e9rale d&#8217;approbation des comptes de l&#8217;exercice. Ensuite, la part de chaque associ\u00e9 est proportionnelle \u00e0 son nombre de parts dans le capital (sauf dispositions diff\u00e9rentes des statuts \u00e0 ce sujet). &nbsp; Ne pas oublier de d\u00e9duire au pr\u00e9alable de la somme \u00e0 verser \u00e0 chacun le montant des\u00a0pr\u00e9l\u00e8vements sociaux\u00a0et le cas \u00e9ch\u00e9ant du\u00a0pr\u00e9l\u00e8vement fiscal,\u00a0lesquels devront \u00eatre revers\u00e9s par votre soci\u00e9t\u00e9. &nbsp; Comment proc\u00e9der au paiement des dividendes\u00a0? Le paiement peut \u00eatre effectu\u00e9 par tout moyen. Il peut aussi \u00eatre effectu\u00e9 en une ou plusieurs fois, mais \u00e0 condition que la totalit\u00e9 soit vers\u00e9e dans les\u00a0neuf mois\u00a0qui suivent la cl\u00f4ture de l&#8217;exercice. &nbsp; Que faire lorsqu\u2019un associ\u00e9 a c\u00e9d\u00e9 ses parts\u00a0? Les dividendes reviennent \u00e0 l\u2019associ\u00e9 qui est propri\u00e9taire des parts, non pas \u00e0 la date de la cl\u00f4ture de l\u2019exercice, pas m\u00eame \u00e0 la date de la distribution, mais \u00e0 la [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.wiredcpa.com\/fr\/date-limite-de-paiement-des-dividendes-cest-le-30-septembre\/\" \/>\n<meta property=\"og:site_name\" content=\"Wired\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wiredcpa\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-09-14T09:15:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.wiredcpa.com\/wp-content\/uploads\/2020\/12\/wired-compta-musique.png\" \/>\n\t<meta property=\"og:image:width\" content=\"2363\" \/>\n\t<meta property=\"og:image:height\" content=\"708\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.wiredcpa.com\/fr\/#organization\",\"name\":\"Wired Expertise Comptable - Musique, Label & Artistes\",\"url\":\"https:\/\/www.wiredcpa.com\/fr\/\",\"sameAs\":[\"https:\/\/www.facebook.com\/wiredcpa\/\"],\"logo\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.wiredcpa.com\/fr\/#logo\",\"inLanguage\":\"fr-FR\",\"url\":\"https:\/\/www.wiredcpa.com\/wp-content\/uploads\/2020\/12\/wired-compta-musique.png\",\"contentUrl\":\"https:\/\/www.wiredcpa.com\/wp-content\/uploads\/2020\/12\/wired-compta-musique.png\",\"width\":2363,\"height\":708,\"caption\":\"Wired Expertise Comptable - Musique, Label & Artistes\"},\"image\":{\"@id\":\"https:\/\/www.wiredcpa.com\/fr\/#logo\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.wiredcpa.com\/fr\/#website\",\"url\":\"https:\/\/www.wiredcpa.com\/fr\/\",\"name\":\"Wired\",\"description\":\"Business sounds better with us\",\"publisher\":{\"@id\":\"https:\/\/www.wiredcpa.com\/fr\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.wiredcpa.com\/fr\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.wiredcpa.com\/fr\/date-limite-de-paiement-des-dividendes-cest-le-30-septembre\/#webpage\",\"url\":\"https:\/\/www.wiredcpa.com\/fr\/date-limite-de-paiement-des-dividendes-cest-le-30-septembre\/\",\"name\":\"Date limite de paiement des dividendes - C\u2019est le 30 septembre - Wired\",\"isPartOf\":{\"@id\":\"https:\/\/www.wiredcpa.com\/fr\/#website\"},\"datePublished\":\"2023-09-14T09:15:19+00:00\",\"dateModified\":\"2023-09-14T09:15:19+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.wiredcpa.com\/fr\/date-limite-de-paiement-des-dividendes-cest-le-30-septembre\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.wiredcpa.com\/fr\/date-limite-de-paiement-des-dividendes-cest-le-30-septembre\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.wiredcpa.com\/fr\/date-limite-de-paiement-des-dividendes-cest-le-30-septembre\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.wiredcpa.com\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Date limite de paiement des dividendes &#8211; C\u2019est le 30 septembre\"}]},{\"@type\":\"Article\",\"@id\":\"https:\/\/www.wiredcpa.com\/fr\/date-limite-de-paiement-des-dividendes-cest-le-30-septembre\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.wiredcpa.com\/fr\/date-limite-de-paiement-des-dividendes-cest-le-30-septembre\/#webpage\"},\"author\":{\"@id\":\"https:\/\/www.wiredcpa.com\/fr\/#\/schema\/person\/79819bc24a42a77be938c794914b1360\"},\"headline\":\"Date limite de paiement des dividendes &#8211; C\u2019est le 30 septembre\",\"datePublished\":\"2023-09-14T09:15:19+00:00\",\"dateModified\":\"2023-09-14T09:15:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.wiredcpa.com\/fr\/date-limite-de-paiement-des-dividendes-cest-le-30-septembre\/#webpage\"},\"wordCount\":429,\"publisher\":{\"@id\":\"https:\/\/www.wiredcpa.com\/fr\/#organization\"},\"articleSection\":[\"Non classifi\u00e9(e)\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.wiredcpa.com\/fr\/#\/schema\/person\/79819bc24a42a77be938c794914b1360\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.wiredcpa.com\/fr\/#personlogo\",\"inLanguage\":\"fr-FR\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/2864418bb4d370135dea7c3b68e76446?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/2864418bb4d370135dea7c3b68e76446?s=96&d=mm&r=g\",\"caption\":\"admin\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Date limite de paiement des dividendes - C\u2019est le 30 septembre - Wired","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.wiredcpa.com\/fr\/date-limite-de-paiement-des-dividendes-cest-le-30-septembre\/","og_locale":"fr_FR","og_type":"article","og_title":"Date limite de paiement des dividendes - C\u2019est le 30 septembre - Wired","og_description":"Quand les dividendes sont-ils dus aux associ\u00e9s\u00a0? Les dividendes ne sont dus que lorsque leur versement a \u00e9t\u00e9 d\u00e9cid\u00e9 au pr\u00e9alable par une assembl\u00e9e g\u00e9n\u00e9rale des associ\u00e9s, cette\u00a0d\u00e9cision\u00a0ayant d\u00fb \u00eatre vot\u00e9e par un ou plusieurs associ\u00e9s repr\u00e9sentant\u00a0plus de la moiti\u00e9\u00a0des parts sociales de la SARL. &nbsp; Combien verser aux associ\u00e9s\u00a0? Le montant global \u00e0 distribuer est fix\u00e9 par l&#8217;assembl\u00e9e g\u00e9n\u00e9rale d&#8217;approbation des comptes de l&#8217;exercice. Ensuite, la part de chaque associ\u00e9 est proportionnelle \u00e0 son nombre de parts dans le capital (sauf dispositions diff\u00e9rentes des statuts \u00e0 ce sujet). &nbsp; Ne pas oublier de d\u00e9duire au pr\u00e9alable de la somme \u00e0 verser \u00e0 chacun le montant des\u00a0pr\u00e9l\u00e8vements sociaux\u00a0et le cas \u00e9ch\u00e9ant du\u00a0pr\u00e9l\u00e8vement fiscal,\u00a0lesquels devront \u00eatre revers\u00e9s par votre soci\u00e9t\u00e9. &nbsp; Comment proc\u00e9der au paiement des dividendes\u00a0? Le paiement peut \u00eatre effectu\u00e9 par tout moyen. Il peut aussi \u00eatre effectu\u00e9 en une ou plusieurs fois, mais \u00e0 condition que la totalit\u00e9 soit vers\u00e9e dans les\u00a0neuf mois\u00a0qui suivent la cl\u00f4ture de l&#8217;exercice. &nbsp; Que faire lorsqu\u2019un associ\u00e9 a c\u00e9d\u00e9 ses parts\u00a0? Les dividendes reviennent \u00e0 l\u2019associ\u00e9 qui est propri\u00e9taire des parts, non pas \u00e0 la date de la cl\u00f4ture de l\u2019exercice, pas m\u00eame \u00e0 la date de la distribution, mais \u00e0 la [&hellip;]","og_url":"https:\/\/www.wiredcpa.com\/fr\/date-limite-de-paiement-des-dividendes-cest-le-30-septembre\/","og_site_name":"Wired","article_publisher":"https:\/\/www.facebook.com\/wiredcpa\/","article_published_time":"2023-09-14T09:15:19+00:00","og_image":[{"width":2363,"height":708,"url":"https:\/\/www.wiredcpa.com\/wp-content\/uploads\/2020\/12\/wired-compta-musique.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Organization","@id":"https:\/\/www.wiredcpa.com\/fr\/#organization","name":"Wired Expertise Comptable - Musique, Label & Artistes","url":"https:\/\/www.wiredcpa.com\/fr\/","sameAs":["https:\/\/www.facebook.com\/wiredcpa\/"],"logo":{"@type":"ImageObject","@id":"https:\/\/www.wiredcpa.com\/fr\/#logo","inLanguage":"fr-FR","url":"https:\/\/www.wiredcpa.com\/wp-content\/uploads\/2020\/12\/wired-compta-musique.png","contentUrl":"https:\/\/www.wiredcpa.com\/wp-content\/uploads\/2020\/12\/wired-compta-musique.png","width":2363,"height":708,"caption":"Wired Expertise Comptable - Musique, Label & Artistes"},"image":{"@id":"https:\/\/www.wiredcpa.com\/fr\/#logo"}},{"@type":"WebSite","@id":"https:\/\/www.wiredcpa.com\/fr\/#website","url":"https:\/\/www.wiredcpa.com\/fr\/","name":"Wired","description":"Business sounds better with us","publisher":{"@id":"https:\/\/www.wiredcpa.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.wiredcpa.com\/fr\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.wiredcpa.com\/fr\/date-limite-de-paiement-des-dividendes-cest-le-30-septembre\/#webpage","url":"https:\/\/www.wiredcpa.com\/fr\/date-limite-de-paiement-des-dividendes-cest-le-30-septembre\/","name":"Date limite de paiement des dividendes - C\u2019est le 30 septembre - Wired","isPartOf":{"@id":"https:\/\/www.wiredcpa.com\/fr\/#website"},"datePublished":"2023-09-14T09:15:19+00:00","dateModified":"2023-09-14T09:15:19+00:00","breadcrumb":{"@id":"https:\/\/www.wiredcpa.com\/fr\/date-limite-de-paiement-des-dividendes-cest-le-30-septembre\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.wiredcpa.com\/fr\/date-limite-de-paiement-des-dividendes-cest-le-30-septembre\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.wiredcpa.com\/fr\/date-limite-de-paiement-des-dividendes-cest-le-30-septembre\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.wiredcpa.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Date limite de paiement des dividendes &#8211; C\u2019est le 30 septembre"}]},{"@type":"Article","@id":"https:\/\/www.wiredcpa.com\/fr\/date-limite-de-paiement-des-dividendes-cest-le-30-septembre\/#article","isPartOf":{"@id":"https:\/\/www.wiredcpa.com\/fr\/date-limite-de-paiement-des-dividendes-cest-le-30-septembre\/#webpage"},"author":{"@id":"https:\/\/www.wiredcpa.com\/fr\/#\/schema\/person\/79819bc24a42a77be938c794914b1360"},"headline":"Date limite de paiement des dividendes &#8211; C\u2019est le 30 septembre","datePublished":"2023-09-14T09:15:19+00:00","dateModified":"2023-09-14T09:15:19+00:00","mainEntityOfPage":{"@id":"https:\/\/www.wiredcpa.com\/fr\/date-limite-de-paiement-des-dividendes-cest-le-30-septembre\/#webpage"},"wordCount":429,"publisher":{"@id":"https:\/\/www.wiredcpa.com\/fr\/#organization"},"articleSection":["Non classifi\u00e9(e)"],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.wiredcpa.com\/fr\/#\/schema\/person\/79819bc24a42a77be938c794914b1360","name":"admin","image":{"@type":"ImageObject","@id":"https:\/\/www.wiredcpa.com\/fr\/#personlogo","inLanguage":"fr-FR","url":"https:\/\/secure.gravatar.com\/avatar\/2864418bb4d370135dea7c3b68e76446?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2864418bb4d370135dea7c3b68e76446?s=96&d=mm&r=g","caption":"admin"}}]}},"_links":{"self":[{"href":"https:\/\/www.wiredcpa.com\/fr\/wp-json\/wp\/v2\/posts\/1072"}],"collection":[{"href":"https:\/\/www.wiredcpa.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.wiredcpa.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.wiredcpa.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.wiredcpa.com\/fr\/wp-json\/wp\/v2\/comments?post=1072"}],"version-history":[{"count":1,"href":"https:\/\/www.wiredcpa.com\/fr\/wp-json\/wp\/v2\/posts\/1072\/revisions"}],"predecessor-version":[{"id":1073,"href":"https:\/\/www.wiredcpa.com\/fr\/wp-json\/wp\/v2\/posts\/1072\/revisions\/1073"}],"wp:attachment":[{"href":"https:\/\/www.wiredcpa.com\/fr\/wp-json\/wp\/v2\/media?parent=1072"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.wiredcpa.com\/fr\/wp-json\/wp\/v2\/categories?post=1072"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.wiredcpa.com\/fr\/wp-json\/wp\/v2\/tags?post=1072"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}